{"id":14,"date":"2024-04-19T06:07:28","date_gmt":"2024-04-19T06:07:28","guid":{"rendered":"https:\/\/wollorama.at\/widerruf\/"},"modified":"2024-12-03T08:37:51","modified_gmt":"2024-12-03T08:37:51","slug":"widerruf","status":"publish","type":"page","link":"https:\/\/wollorama.at\/en\/widerruf\/","title":{"rendered":"Widerruf"},"content":{"rendered":"<p><strong>Widerrufsrecht<\/strong><\/p>\n<p>Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen.<\/p>\n<p>Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat;<\/p>\n<p>Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns <em>[DI Stefanie Taibl,\u00a0 Gr\u00fcnnergasse 16, 2000 Stockerau, info@wollorama.at] <\/em>mittels einer eindeutigen Erkl\u00e4rung (z.B. ein mit der Post versandter Brief oder E-Mail) \u00fcber Ihren Entschluss, diesen Vertrag zu widerrufen, informieren. Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\n<p><strong>Folgen des Widerrufs<\/strong><\/p>\n<p>Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen vierzehn Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet.<\/p>\n<p>Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.<\/p>\n<p>Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns\u00a0zur\u00fcckzusenden oder zu \u00fcbergeben.<\/p>\n<p>Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der Frist von vierzehn Tagen absenden.<\/p>\n<p>Sie tragen die unmittelbaren Kosten der R\u00fccksendung der Waren.<\/p>\n<p>Sie m\u00fcssen f\u00fcr einen etwaigen Wertverlust der Waren nur aufkommen, wenn dieser Wertverlust auf einen zur Pr\u00fcfung der Beschaffenheit, Eigenschaften und Funktionsweise der Waren nicht notwendigen Umgang mit ihnen zur\u00fcckzuf\u00fchren ist.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Widerrufsrecht Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat; Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns [DI Stefanie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Widerruf - Wollorama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wollorama.at\/en\/widerruf\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Widerruf - Wollorama\" \/>\n<meta property=\"og:description\" content=\"Widerrufsrecht Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat; Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns [DI Stefanie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wollorama.at\/en\/widerruf\/\" \/>\n<meta property=\"og:site_name\" content=\"Wollorama\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/wollorama\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-03T08:37:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wollorama.at\\\/widerruf\\\/\",\"url\":\"https:\\\/\\\/wollorama.at\\\/widerruf\\\/\",\"name\":\"Widerruf - Wollorama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wollorama.at\\\/#website\"},\"datePublished\":\"2024-04-19T06:07:28+00:00\",\"dateModified\":\"2024-12-03T08:37:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wollorama.at\\\/widerruf\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wollorama.at\\\/widerruf\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wollorama.at\\\/widerruf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wollorama.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Widerruf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wollorama.at\\\/#website\",\"url\":\"https:\\\/\\\/wollorama.at\\\/\",\"name\":\"Wollorama\",\"description\":\"Willkommen\",\"publisher\":{\"@id\":\"https:\\\/\\\/wollorama.at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wollorama.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wollorama.at\\\/#organization\",\"name\":\"Wollorama\",\"url\":\"https:\\\/\\\/wollorama.at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/wollorama.at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wollorama.at\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Woll.-rama.png\",\"contentUrl\":\"https:\\\/\\\/wollorama.at\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Woll.-rama.png\",\"width\":2281,\"height\":490,\"caption\":\"Wollorama\"},\"image\":{\"@id\":\"https:\\\/\\\/wollorama.at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/wollorama\",\"https:\\\/\\\/at.pinterest.com\\\/wolloramashop\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Widerruf - Wollorama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wollorama.at\/en\/widerruf\/","og_locale":"en_GB","og_type":"article","og_title":"Widerruf - Wollorama","og_description":"Widerrufsrecht Sie haben das Recht, binnen vierzehn Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt vierzehn Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die Waren in Besitz genommen haben bzw. hat; Um Ihr Widerrufsrecht auszu\u00fcben, m\u00fcssen Sie uns [DI Stefanie [&hellip;]","og_url":"https:\/\/wollorama.at\/en\/widerruf\/","og_site_name":"Wollorama","article_publisher":"https:\/\/facebook.com\/wollorama","article_modified_time":"2024-12-03T08:37:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wollorama.at\/widerruf\/","url":"https:\/\/wollorama.at\/widerruf\/","name":"Widerruf - Wollorama","isPartOf":{"@id":"https:\/\/wollorama.at\/#website"},"datePublished":"2024-04-19T06:07:28+00:00","dateModified":"2024-12-03T08:37:51+00:00","breadcrumb":{"@id":"https:\/\/wollorama.at\/widerruf\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wollorama.at\/widerruf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wollorama.at\/widerruf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wollorama.at\/"},{"@type":"ListItem","position":2,"name":"Widerruf"}]},{"@type":"WebSite","@id":"https:\/\/wollorama.at\/#website","url":"https:\/\/wollorama.at\/","name":"Wollorama","description":"Willkommen","publisher":{"@id":"https:\/\/wollorama.at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wollorama.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/wollorama.at\/#organization","name":"Wollorama","url":"https:\/\/wollorama.at\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/wollorama.at\/#\/schema\/logo\/image\/","url":"https:\/\/wollorama.at\/wp-content\/uploads\/2025\/10\/Woll.-rama.png","contentUrl":"https:\/\/wollorama.at\/wp-content\/uploads\/2025\/10\/Woll.-rama.png","width":2281,"height":490,"caption":"Wollorama"},"image":{"@id":"https:\/\/wollorama.at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/wollorama","https:\/\/at.pinterest.com\/wolloramashop\/"]}]}},"_links":{"self":[{"href":"https:\/\/wollorama.at\/en\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wollorama.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wollorama.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wollorama.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wollorama.at\/en\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":0,"href":"https:\/\/wollorama.at\/en\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"wp:attachment":[{"href":"https:\/\/wollorama.at\/en\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}